{"id":5674,"date":"2024-09-25T19:06:28","date_gmt":"2024-09-25T19:06:28","guid":{"rendered":"https:\/\/eloundavillage.com\/%ce%ba%ce%bb%ce%b1%cf%83%ce%b9%ce%ba%cf%8c-%ce%bc%cf%80%ce%b1%ce%bd%ce%b3%ce%ba%ce%b1%ce%bb%cf%8c%ce%bf%cf%85-%ce%b8%ce%ad%ce%b1-%cf%83%cf%84%ce%bf%ce%bd-%ce%ba%ce%ae%cf%80%ce%bf\/"},"modified":"2025-02-22T00:32:05","modified_gmt":"2025-02-22T00:32:05","slug":"classic-bungalow-garden-view-2","status":"publish","type":"page","link":"https:\/\/eloundavillage.com\/el\/classic-bungalow-garden-view-2\/","title":{"rendered":"Classic Bungalow, Garden View"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.26.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f3eee7&#8243; custom_margin=&#8221;-140px||||false|false&#8221; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_slider _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#FFFFFF&#8221; body_text_color=&#8221;#FFFFFF&#8221; background_enable_image=&#8221;off&#8221; background_position=&#8221;bottom_center&#8221; min_height=&#8221;940px&#8221; min_height_tablet=&#8221;500px&#8221; min_height_phone=&#8221;400px&#8221; min_height_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_slide _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/12\/Classic-Bungalow-Garden-View-01.jpg&#8221; background_enable_image=&#8221;on&#8221; parallax=&#8221;off&#8221; width=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_transition=&#8221;on&#8221;][\/et_pb_slide][\/et_pb_slider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.26.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f3eee7&#8243; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;100px||2px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;70%&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px||1px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.26.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;italiana-regular&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#313131&#8243; text_font_size=&#8221;32px&#8221; text_line_height=&#8221;1.2em&#8221; min_height=&#8221;43.8px&#8221; custom_margin=&#8221;||30px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Classic Bungalow, Garden View<\/p>\n<div id=\"awebChromeHelper\"><\/div>\n<div id=\"awebChromeHelper\"><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;70%&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px||50px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.26.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>\u0388\u03bd\u03b1 \u03b1\u03c0\u03bf\u03bc\u03bf\u03bd\u03c9\u03bc\u03ad\u03bd\u03bf \u03ba\u03b1\u03c4\u03b1\u03c6\u03cd\u03b3\u03b9\u03bf \u03c3\u03c4\u03bf\u03c5\u03c2 \u03ba\u03b1\u03c4\u03b1\u03c0\u03c1\u03ac\u03c3\u03b9\u03bd\u03bf\u03c5\u03c2 \u03ba\u03ae\u03c0\u03bf\u03c5\u03c2 \u03c4\u03bf\u03c5 \u03b8\u03b5\u03c1\u03ad\u03c4\u03c1\u03bf\u03c5, \u03b1\u03c5\u03c4\u03cc \u03c4\u03bf \u03c0\u03c1\u03bf\u03c3\u03b5\u03b3\u03bc\u03ad\u03bd\u03bf \u03bc\u03c0\u03b1\u03bd\u03b3\u03ba\u03b1\u03bb\u03cc\u03bf\u03c5 \u03c0\u03c1\u03bf\u03c3\u03c6\u03ad\u03c1\u03b5\u03b9 \u03c4\u03b7\u03bd \u03c4\u03ad\u03bb\u03b5\u03b9\u03b1 \u03b2\u03ac\u03c3\u03b7 \u03b3\u03b9\u03b1 \u03bf\u03bd\u03b5\u03b9\u03c1\u03b5\u03bc\u03ad\u03bd\u03b5\u03c2 \u03b4\u03b9\u03b1\u03ba\u03bf\u03c0\u03ad\u03c2 \u03c3\u03c4\u03b7\u03bd \u03ba\u03bf\u03c3\u03bc\u03bf\u03c0\u03bf\u03bb\u03af\u03c4\u03b9\u03ba\u03b7 \u0395\u03bb\u03bf\u03cd\u03bd\u03c4\u03b1. \u0394\u03b9\u03b1\u03ba\u03bf\u03c3\u03bc\u03b7\u03bc\u03ad\u03bd\u03bf \u03bc\u03b5 \u03b3\u03bf\u03cd\u03c3\u03c4\u03bf, \u03b4\u03b9\u03b1\u03b8\u03ad\u03c4\u03b5\u03b9 \u03b1\u03c0\u03b1\u03bb\u03bf\u03cd\u03c2 \u03b3\u03ae\u03b9\u03bd\u03bf\u03c5\u03c2 \u03c4\u03cc\u03bd\u03bf\u03c5\u03c2 \u03ba\u03b1\u03b9 \u03bc\u03bf\u03bd\u03c4\u03ad\u03c1\u03bd\u03b1 \u03be\u03cd\u03bb\u03b9\u03bd\u03b1 \u03ad\u03c0\u03b9\u03c0\u03bb\u03b1, \u03b4\u03b7\u03bc\u03b9\u03bf\u03c5\u03c1\u03b3\u03ce\u03bd\u03c4\u03b1\u03c2 \u03bc\u03b9\u03b1 \u03c7\u03b1\u03bb\u03b1\u03c1\u03c9\u03c4\u03b9\u03ba\u03ae \u03ba\u03b1\u03b9 \u03c6\u03b9\u03bb\u03cc\u03be\u03b5\u03bd\u03b7 \u03b1\u03c4\u03bc\u03cc\u03c3\u03c6\u03b1\u03b9\u03c1\u03b1. \u0391\u03c0\u03bf\u03bb\u03b1\u03cd\u03c3\u03c4\u03b5 \u03c3\u03c4\u03b9\u03b3\u03bc\u03ad\u03c2 \u03ae\u03c1\u03b5\u03bc\u03b7\u03c2 \u03c0\u03b5\u03c1\u03b9\u03c3\u03c5\u03bb\u03bb\u03bf\u03b3\u03ae\u03c2 \u03c3\u03c4\u03b7\u03bd \u03b9\u03b4\u03b9\u03c9\u03c4\u03b9\u03ba\u03ae \u03c3\u03b1\u03c2 \u03b2\u03b5\u03c1\u03ac\u03bd\u03c4\u03b1, \u03c0\u03bf\u03c5 \u03c0\u03b5\u03c1\u03b9\u03b2\u03ac\u03bb\u03bb\u03b5\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03b5\u03c5\u03c9\u03b4\u03b9\u03b1\u03c3\u03c4\u03ac \u03ac\u03bd\u03b8\u03b7 \u03ba\u03b1\u03b9 \u03c4\u03bf\u03c5\u03c2 \u03c7\u03b1\u03bb\u03b1\u03c1\u03c9\u03c4\u03b9\u03ba\u03bf\u03cd\u03c2 \u03ae\u03c7\u03bf\u03c5\u03c2 \u03c4\u03b7\u03c2 \u03c6\u03cd\u03c3\u03b7\u03c2. \u0391\u03bd\u03b1\u03bd\u03b5\u03c9\u03b8\u03b5\u03af\u03c4\u03b5 \u03c3\u03c4\u03bf \u03c0\u03bf\u03bb\u03c5\u03c4\u03b5\u03bb\u03ad\u03c2 \u03bc\u03b1\u03c1\u03bc\u03ac\u03c1\u03b9\u03bd\u03bf \u03bc\u03c0\u03ac\u03bd\u03b9\u03bf \u03bc\u03b5\u03c4\u03ac \u03b1\u03c0\u03cc \u03bc\u03b9\u03b1 \u03bc\u03ad\u03c1\u03b1 \u03b5\u03be\u03b5\u03c1\u03b5\u03cd\u03bd\u03b7\u03c3\u03b7\u03c2.<\/p>\n<div id=\"awebChromeHelper\"><\/div>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/aquilaeloundavillage.reserve-online.net\/?_ga=2.144844852.1085921262.1718554969-1726060018.1708244718&#038;_gac=1.183191380.1715445894.CjwKCAjwrvyxBhAbEiwAEg_KgtHKkZ9l2vvLEGNDIn6hL70cyeJTavuHCgKXcfBNpdvRg4VjW1glnBoC1fMQAvD_BwE&#038;_gl=1*ptxk0*_gcl_aw*R0NMLjE3MTU0NDU4OTQuQ2p3S0NBandydnl4QmhBYkVpd0FFZ19LZ3RIS2taOWwydnZMRUdOREluNmhMNzBjeWVKVGF2dUhDZ0tYY2ZCTnBkdlJnNFZqVzFnbG5Cb0MxZk1RQXZEX0J3RQ..*_gcl_au*MTU0NTU2NjAzMC4xNzE2MDQ0NTQz*_ga*MTcyNjA2MDAxOC4xNzA4MjQ0NzE4*_ga_GPDKE8MRTC*MTcxODU1NzgzNy4zNC4wLjE3MTg1NTc4MzcuNjAuMC4w&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;\u0394\u03b5\u03af\u03c4\u03b5 \u03a4\u03b9\u03bc\u03ad\u03c2&#8221; admin_label=&#8221;Button&#8221; module_class=&#8221;fullwidthBTN&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;17px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;rgba(182,164,134,0.66)&#8221; button_border_color=&#8221;rgba(182,164,134,0.66)&#8221; custom_margin=&#8221;10px||0px||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.26.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_line_height=&#8221;2.3em&#8221; custom_margin=&#8221;||-1px|||&#8221; custom_padding=&#8221;0px||9px||false|false&#8221; border_radii=&#8221;on|1px|1px|1px|1px&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#b6a486&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/08\/eye-1.png\" width=\"16\" height=\"16\" alt=\"\" class=\"wp-image-1759 alignnone size-full\" \/><\/strong> \u0398\u03ad\u03b1 \u0398\u03ac\u03bb\u03b1\u03c3\u03c3\u03b1<br \/><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/08\/A-adult.png\" width=\"16\" height=\"16\" alt=\"\" class=\"wp-image-1759 alignnone size-full\" \/> \u039c\u03ad\u03b3\u03b9\u03c3\u03c4\u03bf\u03c2 \u03b1\u03c1\u03b9\u03b8\u03bc\u03cc\u03c2 \u03b1\u03c4\u03cc\u03bc\u03c9\u03bd: 3 \u03b5\u03bd\u03ae\u03bb\u03b9\u03ba\u03b5\u03c2<br \/><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/08\/a-arrow.png\" width=\"16\" height=\"16\" alt=\"\" class=\"wp-image-1759 alignnone size-full\" \/> 28 m\u00b2<br \/><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/08\/a-bed.png\" width=\"16\" height=\"16\" alt=\"\" class=\"wp-image-1759 alignnone size-full\" \/>\u00a0K\u03c1\u03b5\u03b2\u03ac\u03c4\u03b9 King Size<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/09\/Bungalow_Garden-View.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;View Floor plan&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#b6a486&#8243; button_bg_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_color=&#8221;#b6a486&#8243; button_icon=&#8221;&#x22;||divi||400&#8243; button_icon_color=&#8221;#b6a486&#8243; button_on_hover=&#8221;off&#8221; custom_margin=&#8221;16px||15px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; width=&#8221;100%&#8221; width_tablet=&#8221;70%&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.26.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div id=\"metaslider-id-5107\" style=\"width: 100%;\" class=\"ml-slider-3-110-0 metaslider metaslider-flex metaslider-5107 ml-slider has-carousel-mode ms-theme-default nav-hidden\" role=\"region\" aria-label=\"Classic Bungalow, Garden View\" data-height=\"525\" data-width=\"800\">\n    <div id=\"metaslider_container_5107\">\n        <div id=\"metaslider_5107\">\n            <ul class='slides'>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5110 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-26 10:56:20\" data-filename=\"Classic-Bungalow-Garden-View-01-1-2-800x525.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/12\/Classic-Bungalow-Garden-View-01-1-2-800x525.jpg\" height=\"525\" width=\"800\" alt=\"Luxury Adults Only hotel in Crete\" class=\"slider-5107 slide-5110 msDefaultImage\" title=\"Luxury Adults Only hotel in Crete\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5115 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-26 10:56:22\" data-filename=\"Classic-Bungalow-Garden-View-02-2-800x525.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/12\/Classic-Bungalow-Garden-View-02-2-800x525.jpg\" height=\"525\" width=\"800\" alt=\"Luxury Adults Only hotel in Crete\" class=\"slider-5107 slide-5115 msDefaultImage\" title=\"Luxury Adults Only hotel in Crete\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5113 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-26 10:56:21\" data-filename=\"Classic-Bungalow-Garden-View-05-2-800x525.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/12\/Classic-Bungalow-Garden-View-05-2-800x525.jpg\" height=\"525\" width=\"800\" alt=\"Luxury Adults Only hotel in Crete\" class=\"slider-5107 slide-5113 msDefaultImage\" title=\"Luxury Adults Only hotel in Crete\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5108 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-26 10:56:19\" data-filename=\"Classic-Bungalow-Garden-View-04-2-800x525.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/12\/Classic-Bungalow-Garden-View-04-2-800x525.jpg\" height=\"525\" width=\"800\" alt=\"Luxury Adults Only hotel in Crete\" class=\"slider-5107 slide-5108 msDefaultImage\" title=\"Luxury Adults Only hotel in Crete\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5111 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-26 10:56:21\" data-filename=\"elounda_-classic-bungalow_garden_view_1-800x525.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/10\/elounda_-classic-bungalow_garden_view_1-800x525.jpg\" height=\"525\" width=\"800\" alt=\"elounda classic bungalow garden view\" class=\"slider-5107 slide-5111 msDefaultImage\" title=\"elounda classic bungalow garden view\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5109 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-26 10:56:20\" data-filename=\"Classic-Bungalow-Garden-View-03-2-800x525.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/12\/Classic-Bungalow-Garden-View-03-2-800x525.jpg\" height=\"525\" width=\"800\" alt=\"Luxury Adults Only hotel in Crete\" class=\"slider-5107 slide-5109 msDefaultImage\" title=\"Luxury Adults Only hotel in Crete\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5112 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-26 10:56:21\" data-filename=\"elounda_-classic-bungalow_garden_view_3-800x525.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/10\/elounda_-classic-bungalow_garden_view_3-800x525.jpg\" height=\"525\" width=\"800\" alt=\"elounda classic bungalow garden view\" class=\"slider-5107 slide-5112 msDefaultImage\" title=\"elounda classic bungalow garden view\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5114 ms-image \" aria-roledescription=\"slide\" data-date=\"2024-12-26 10:56:22\" data-filename=\"elounda_-classic-bungalow_garden_view_2-800x525.jpg\" data-slide-type=\"image\"><img decoding=\"async\" src=\"https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/10\/elounda_-classic-bungalow_garden_view_2-800x525.jpg\" height=\"525\" width=\"800\" alt=\"elounda classic bungalow garden view\" class=\"slider-5107 slide-5114 msDefaultImage\" title=\"elounda classic bungalow garden view\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.26.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;50px||50px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; width=&#8221;70%&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; max_width=&#8221;2560px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;et_pb_slide_titleDifference&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#313131&#8243; text_font_size=&#8221;26px&#8221; text_letter_spacing=&#8221;1px&#8221; text_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;0px|0px|0px|0px|false|false&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>All stays include<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|false|false&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li>\u0395\u03c0\u03b9\u03bb\u03b5\u03b3\u03bc\u03ad\u03bd\u03b1 \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03b1 \u03c0\u03b5\u03c1\u03b9\u03c0\u03bf\u03af\u03b7\u03c3\u03b7\u03c2<\/li>\n<li>\u039c\u03c0\u03bf\u03c5\u03c1\u03bd\u03bf\u03cd\u03b6\u03b9\u03b1<\/li>\n<li>\u03a3\u03c4\u03b5\u03b3\u03bd\u03c9\u03c4\u03ae\u03c1\u03b1 \u03bc\u03b1\u03bb\u03bb\u03b9\u03ce\u03bd<\/li>\n<li>\u0395\u03c0\u03b9\u03bb\u03bf\u03b3\u03ae \u03bc\u03b1\u03be\u03b9\u03bb\u03b1\u03c1\u03b9\u03bf\u03cd<\/li>\n<li>\u03a0\u03b5\u03c4\u03c3\u03ad\u03c4\u03b5\u03c2 \u03c0\u03b1\u03c1\u03b1\u03bb\u03af\u03b1\u03c2<\/li>\n<li>\u03a3\u03c5\u03c3\u03ba\u03b5\u03c5\u03ad\u03c2 \u03b3\u03b9\u03b1 \u03c4\u03c3\u03ac\u03b9\/\u03ba\u03b1\u03c6\u03ad<\/li>\n<li>\u03a8\u03b7\u03c6\u03b9\u03b1\u03ba\u03cc \u03c7\u03c1\u03b7\u03bc\u03b1\u03c4\u03bf\u03ba\u03b9\u03b2\u03ce\u03c4\u03b9\u03bf<\/li>\n<li>\u0386\u03bc\u03b5\u03c3\u03b7 \u03c4\u03b7\u03bb\u03b5\u03c6\u03c9\u03bd\u03b9\u03ba\u03ae \u03b3\u03c1\u03b1\u03bc\u03bc\u03ae<\/li>\n<li>Smart <span>\u03b4\u03bf\u03c1\u03c5\u03c6\u03bf\u03c1\u03b9\u03ba\u03ae \u03c4\u03b7\u03bb\u03b5\u03cc\u03c1\u03b1\u03c3\u03b7 <\/span>LCD 43\u2033 \u03bc\u03b5 \u03b5\u03bd\u03c3\u03c9\u03bc\u03b1\u03c4\u03c9\u03bc\u03ad\u03bd\u03b1 \u03c1\u03b1\u03b4\u03b9\u03bf\u03c6\u03c9\u03bd\u03b9\u03ba\u03ac \u03ba\u03b1\u03b9 \u03bc\u03bf\u03c5\u03c3\u03b9\u03ba\u03ac \u03ba\u03b1\u03bd\u03ac\u03bb\u03b9\u03b1<\/li>\n<li>\u039c\u03af\u03bd\u03b9 \u03bc\u03c0\u03b1\u03c1<\/li>\n<li>\u039a\u03bb\u03b9\u03bc\u03b1\u03c4\u03b9\u03c3\u03bc\u03cc\/\u03b8\u03ad\u03c1\u03bc\u03b1\u03bd\u03c3\u03b7<\/li>\n<li>\u039a\u03b1\u03bb\u03c9\u03c3\u03cc\u03c1\u03b9\u03c3\u03bc\u03b1 \u03bc\u03b5 \u03b3\u03bb\u03c5\u03ba\u03af\u03c3\u03bc\u03b1\u03c4\u03b1 \u03ba\u03b1\u03c4\u03ac \u03c4\u03b7\u03bd \u03ac\u03c6\u03b9\u03be\u03b7<\/li>\n<li>\u03a0\u03c1\u03cc\u03c3\u03b2\u03b1\u03c3\u03b7 \u03c3\u03b5 \u03cc\u03bb\u03b5\u03c2 \u03c4\u03b9\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03b1\u03c3\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2 \u03b1\u03bd\u03b1\u03c8\u03c5\u03c7\u03ae\u03c2, \u03cc\u03c0\u03c9\u03c2 \u03b5\u03c3\u03c9\u03c4\u03b5\u03c1\u03b9\u03ba\u03ae \u03b8\u03b5\u03c1\u03bc\u03b1\u03b9\u03bd\u03cc\u03bc\u03b5\u03bd\u03b7 \u03c0\u03b9\u03c3\u03af\u03bd\u03b1, \u03c3\u03ac\u03bf\u03c5\u03bd\u03b1, \u03b3\u03c5\u03bc\u03bd\u03b1\u03c3\u03c4\u03ae\u03c1\u03b9\u03bf, \u03b3\u03ae\u03c0\u03b5\u03b4\u03bf \u03c4\u03ad\u03bd\u03b9\u03c2 \u03ba\u03b1\u03b9 \u03b5\u03be\u03c9\u03c4\u03b5\u03c1\u03b9\u03ba\u03cc \u03c5\u03b4\u03c1\u03bf\u03bc\u03b1\u03c3\u03ac\u03b6<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.26.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f3eee7&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; width=&#8221;70%&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; max_width=&#8221;2560px&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;et_pb_slide_titleDifference&#8221; _builder_version=&#8221;4.26.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#313131&#8243; text_font_size=&#8221;26px&#8221; text_letter_spacing=&#8221;1px&#8221; text_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;-1px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\">Other suggestions<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;70%&#8221; width_tablet=&#8221;70%&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; max_width=&#8221;2560px&#8221; custom_margin=&#8221;20px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.26.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/12\/Classic-Room-Garden-View-01.jpg&#8221; title_text=&#8221;Classic Room, Garden View 01&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; scroll_fade_enable=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;mainTitleHome&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#313131&#8243; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;1.2em&#8221; min_height=&#8221;53px&#8221; custom_margin=&#8221;0px||10px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Classic Bungalow, Sea View<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjI1NDQifX0=@&#8221; button_text=&#8221;\u039b\u03b5\u03c0\u03c4\u03bf\u03bc\u03ad\u03c1\u03b5\u03b9\u03b5\u03c2&#8221; admin_label=&#8221;Button&#8221; module_class=&#8221;fullwidthBTN&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;17px&#8221; button_text_color=&#8221;#b6a486&#8243; button_bg_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_color=&#8221;rgba(182,164,134,0.66)&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.26.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/eloundavillage.com\/wp-content\/uploads\/2024\/12\/Mythica-Superior-Suite-Sea-View-01.jpg&#8221; title_text=&#8221;Mythica Superior Suite, Sea View 01&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; scroll_fade_enable=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text module_class=&#8221;mainTitleHome&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#313131&#8243; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;1.2em&#8221; min_height=&#8221;53px&#8221; custom_margin=&#8221;0px||10px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Mythica Superior Suite, Sea View<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjI2MTgifX0=@&#8221; button_text=&#8221;\u039b\u03b5\u03c0\u03c4\u03bf\u03bc\u03ad\u03c1\u03b5\u03b9\u03b5\u03c2&#8221; admin_label=&#8221;Button&#8221; module_class=&#8221;fullwidthBTN&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;17px&#8221; button_text_color=&#8221;#b6a486&#8243; button_bg_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_color=&#8221;rgba(182,164,134,0.66)&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Classic Bungalow, Garden View \u0388\u03bd\u03b1 \u03b1\u03c0\u03bf\u03bc\u03bf\u03bd\u03c9\u03bc\u03ad\u03bd\u03bf \u03ba\u03b1\u03c4\u03b1\u03c6\u03cd\u03b3\u03b9\u03bf \u03c3\u03c4\u03bf\u03c5\u03c2 \u03ba\u03b1\u03c4\u03b1\u03c0\u03c1\u03ac\u03c3\u03b9\u03bd\u03bf\u03c5\u03c2 \u03ba\u03ae\u03c0\u03bf\u03c5\u03c2 \u03c4\u03bf\u03c5 \u03b8\u03b5\u03c1\u03ad\u03c4\u03c1\u03bf\u03c5, \u03b1\u03c5\u03c4\u03cc \u03c4\u03bf \u03c0\u03c1\u03bf\u03c3\u03b5\u03b3\u03bc\u03ad\u03bd\u03bf \u03bc\u03c0\u03b1\u03bd\u03b3\u03ba\u03b1\u03bb\u03cc\u03bf\u03c5 \u03c0\u03c1\u03bf\u03c3\u03c6\u03ad\u03c1\u03b5\u03b9 \u03c4\u03b7\u03bd \u03c4\u03ad\u03bb\u03b5\u03b9\u03b1 \u03b2\u03ac\u03c3\u03b7 \u03b3\u03b9\u03b1 \u03bf\u03bd\u03b5\u03b9\u03c1\u03b5\u03bc\u03ad\u03bd\u03b5\u03c2 \u03b4\u03b9\u03b1\u03ba\u03bf\u03c0\u03ad\u03c2 \u03c3\u03c4\u03b7\u03bd \u03ba\u03bf\u03c3\u03bc\u03bf\u03c0\u03bf\u03bb\u03af\u03c4\u03b9\u03ba\u03b7 \u0395\u03bb\u03bf\u03cd\u03bd\u03c4\u03b1. \u0394\u03b9\u03b1\u03ba\u03bf\u03c3\u03bc\u03b7\u03bc\u03ad\u03bd\u03bf \u03bc\u03b5 \u03b3\u03bf\u03cd\u03c3\u03c4\u03bf, \u03b4\u03b9\u03b1\u03b8\u03ad\u03c4\u03b5\u03b9 \u03b1\u03c0\u03b1\u03bb\u03bf\u03cd\u03c2 \u03b3\u03ae\u03b9\u03bd\u03bf\u03c5\u03c2 \u03c4\u03cc\u03bd\u03bf\u03c5\u03c2 \u03ba\u03b1\u03b9 \u03bc\u03bf\u03bd\u03c4\u03ad\u03c1\u03bd\u03b1 \u03be\u03cd\u03bb\u03b9\u03bd\u03b1 \u03ad\u03c0\u03b9\u03c0\u03bb\u03b1, \u03b4\u03b7\u03bc\u03b9\u03bf\u03c5\u03c1\u03b3\u03ce\u03bd\u03c4\u03b1\u03c2 \u03bc\u03b9\u03b1 \u03c7\u03b1\u03bb\u03b1\u03c1\u03c9\u03c4\u03b9\u03ba\u03ae \u03ba\u03b1\u03b9 \u03c6\u03b9\u03bb\u03cc\u03be\u03b5\u03bd\u03b7 \u03b1\u03c4\u03bc\u03cc\u03c3\u03c6\u03b1\u03b9\u03c1\u03b1. \u0391\u03c0\u03bf\u03bb\u03b1\u03cd\u03c3\u03c4\u03b5 \u03c3\u03c4\u03b9\u03b3\u03bc\u03ad\u03c2 \u03ae\u03c1\u03b5\u03bc\u03b7\u03c2 \u03c0\u03b5\u03c1\u03b9\u03c3\u03c5\u03bb\u03bb\u03bf\u03b3\u03ae\u03c2 \u03c3\u03c4\u03b7\u03bd \u03b9\u03b4\u03b9\u03c9\u03c4\u03b9\u03ba\u03ae \u03c3\u03b1\u03c2 \u03b2\u03b5\u03c1\u03ac\u03bd\u03c4\u03b1, \u03c0\u03bf\u03c5 \u03c0\u03b5\u03c1\u03b9\u03b2\u03ac\u03bb\u03bb\u03b5\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03b5\u03c5\u03c9\u03b4\u03b9\u03b1\u03c3\u03c4\u03ac [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-5674","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/eloundavillage.com\/el\/wp-json\/wp\/v2\/pages\/5674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eloundavillage.com\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eloundavillage.com\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eloundavillage.com\/el\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/eloundavillage.com\/el\/wp-json\/wp\/v2\/comments?post=5674"}],"version-history":[{"count":8,"href":"https:\/\/eloundavillage.com\/el\/wp-json\/wp\/v2\/pages\/5674\/revisions"}],"predecessor-version":[{"id":12581,"href":"https:\/\/eloundavillage.com\/el\/wp-json\/wp\/v2\/pages\/5674\/revisions\/12581"}],"wp:attachment":[{"href":"https:\/\/eloundavillage.com\/el\/wp-json\/wp\/v2\/media?parent=5674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}